{"id":10520,"date":"2025-07-13T20:52:22","date_gmt":"2025-07-13T18:52:22","guid":{"rendered":"https:\/\/www.castingnews.eu\/magazine\/?p=10520"},"modified":"2025-07-13T20:52:24","modified_gmt":"2025-07-13T18:52:24","slug":"valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona","status":"publish","type":"post","link":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/","title":{"rendered":"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona"},"content":{"rendered":"\n<p>Sono ufficialmente iniziate a <strong>Verona <\/strong>le riprese del film <em><strong>Non \u00e8 la fine del mondo<\/strong><\/em>, adattamento cinematografico del romanzo bestseller di Alessia Gazzola. Dopo un primo blocco girato a marzo a Roma, la produzione si \u00e8 trasferita nella citt\u00e0 scaligera per realizzare la maggior parte degli interni e alcune sequenze in esterna, trasformando Verona in un vivace set cinematografico.<\/p><div class=\"6d3639e8c6ac292cde400fad8ff8a5b9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Casting Bambini NEW -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:336px;height:280px\"\r\n     data-ad-client=\"ca-pub-5538097485429833\"\r\n     data-ad-slot=\"5127154445\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n\n\n\n\n<p>La regia \u00e8 affidata a <strong>Valentina Zanella<\/strong>, che firma il progetto insieme alla casa di produzione veronese K Plus Film, con il sostegno della Fondazione Veneto Film Commission. Un&#8217;importante operazione culturale e produttiva che mira a promuovere il territorio, generando ricadute economiche dirette e occupazione: oltre cinquanta tra tecnici, maestranze e fornitori locali sono infatti coinvolti nella realizzazione del film.<\/p>\n\n\n\n<p>Il cast riunisce volti noti e apprezzati del panorama cinematografico italiano: <strong>Fotin\u00ec Peluso<\/strong> nel ruolo della protagonista, <strong>Andrea Bosca<\/strong>, <strong>Paolo Ruffini<\/strong> e <strong>Paolo Rossi<\/strong>. Le riprese proseguiranno fino alla fine di luglio tra Verona e provincia, mentre la post-produzione si concluder\u00e0 entro la fine dell\u2019anno. L\u2019uscita nelle sale \u00e8 prevista per il 2026.<\/p>\n\n\n\n<p><strong>Il racconto di Emma: sogni, inciampi e nuove partenze<br><\/strong>La storia ruota attorno alla giovane Emma De Tessent, ventottenne dallo spirito ironico e romantico, met\u00e0 inglese e con una passione viscerale per la sua bicicletta gialla, con cui attraversa Roma in cerca di un posto nel mondo. Eterna stagista in una casa di produzione, Emma vive tra sogni e fallimenti, cadute e ripartenze, trovandosi a ricominciare pi\u00f9 volte da zero: da disoccupata a commessa in un negozio per bambini, fino a un\u2019insperata carriera editoriale.<\/p>\n\n\n\n<p>\u201cNon \u00e8 la fine del mondo\u201d non \u00e8 solo il titolo del film, ma anche il mantra con cui Emma affronta le sfide quotidiane. Una commedia sentimentale che esplora con leggerezza e profondit\u00e0 il precariato giovanile, le ambizioni professionali, i compromessi e le domande esistenziali che ogni trentenne, almeno una volta, si \u00e8 posto.<\/p>\n\n\n\n<p><strong>Iscriviti alla\u00a0<a href=\"https:\/\/www.castingnewsletter.eu\/CastingNewsPro\/\" target=\"_blank\" rel=\"noreferrer noopener\">newsletter giornaliera<\/a>\u00a0di Casting News Professional per ricevere le ultime notizie sui casting aperti, provini e audizioni.<\/strong><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Sono ufficialmente iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, adattamento cinematografico del romanzo bestseller di Alessia Gazzola. Dopo un primo blocco girato a marzo a Roma, la produzione si \u00e8 trasferita nella citt\u00e0 scaligera per realizzare la maggior parte degli interni e alcune sequenze in esterna, trasformando Verona in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[61,1533,71,21,30,34,3971],"tags":[6929,8214,8222,272,273,8215,8221,8217,8219,7134,8223,8213,8218,8212,8224,8225,8220,8211,8216],"class_list":{"0":"post-10520","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-commedia","8":"category-featured","9":"category-italia-paese","10":"category-in-primo-piano","11":"category-progetti-cinematografici","12":"category-romantico","13":"category-veneto","14":"tag-adattamento-cinematografico","15":"tag-alessia-gazzola-romanzo","16":"tag-andrea-bosca-attore","17":"tag-casting-magazine","18":"tag-casting-news","19":"tag-cinema-italiano-2026","20":"tag-distribuzione-film-2026","21":"tag-film-girato-a-verona","22":"tag-film-italiani-2025","23":"tag-film-tratto-da-romanzo","24":"tag-fondazione-veneto-film-commission","25":"tag-fotini-peluso-attrice","26":"tag-k-plus-film","27":"tag-non-e-la-fine-del-mondo-film","28":"tag-paolo-rossi-attore","29":"tag-paolo-ruffini-cast","30":"tag-produzione-cinematografica-verona","31":"tag-riprese-verona","32":"tag-valentina-zanella-regista"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona - Casting News Magazine<\/title>\r\n<meta name=\"description\" content=\"Sono iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, diretto da Valentina Zanella e tratto dal romanzo di Alessia Gazzola.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona - Casting News Magazine\" \/>\r\n<meta property=\"og:description\" content=\"Sono iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, diretto da Valentina Zanella e tratto dal romanzo di Alessia Gazzola.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Casting News Magazine\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-07-13T18:52:22+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-07-13T18:52:24+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.castingnews.eu\/magazine\/wp-content\/uploads\/2025\/07\/Verona-Veneto-film-Casting-News.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"670\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Redazione\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/#\\\/schema\\\/person\\\/099d71c568c9a7e5e4037b1594108f17\"},\"headline\":\"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona\",\"datePublished\":\"2025-07-13T18:52:22+00:00\",\"dateModified\":\"2025-07-13T18:52:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/\"},\"wordCount\":342,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Verona-Veneto-film-Casting-News.jpg\",\"keywords\":[\"adattamento cinematografico\",\"Alessia Gazzola romanzo\",\"Andrea Bosca attore\",\"Casting Magazine\",\"Casting News\",\"cinema italiano 2026\",\"distribuzione film 2026\",\"film girato a Verona\",\"film italiani 2025\",\"film tratto da romanzo\",\"Fondazione Veneto Film Commission\",\"Fotin\u00ec Peluso attrice\",\"K Plus Film\",\"Non \u00e8 la fine del mondo film\",\"Paolo Rossi attore\",\"Paolo Ruffini cast\",\"produzione cinematografica Verona\",\"riprese Verona\",\"Valentina Zanella regista\"],\"articleSection\":[\"Commedia\",\"In primo piano\",\"Italia\",\"Primo piano\",\"Progetti cinematografici\",\"Romantico\",\"Veneto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/\",\"url\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/\",\"name\":\"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona - Casting News Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Verona-Veneto-film-Casting-News.jpg\",\"datePublished\":\"2025-07-13T18:52:22+00:00\",\"dateModified\":\"2025-07-13T18:52:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/#\\\/schema\\\/person\\\/099d71c568c9a7e5e4037b1594108f17\"},\"description\":\"Sono iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, diretto da Valentina Zanella e tratto dal romanzo di Alessia Gazzola.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Verona-Veneto-film-Casting-News.jpg\",\"contentUrl\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Verona-Veneto-film-Casting-News.jpg\",\"width\":1200,\"height\":670,\"caption\":\"Riprese a Verona per il film \u201cNon \u00e8 la fine del mondo\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/2025\\\/07\\\/13\\\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/\",\"name\":\"Casting News Magazine\",\"description\":\"News e aggiornamenti sui film, serie tv, teatro e festival italiani ed internazionali\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/#\\\/schema\\\/person\\\/099d71c568c9a7e5e4037b1594108f17\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73a087aa3bd279fb70d24f1960a91c82cf67619395b60b564c90e9e5d5325fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73a087aa3bd279fb70d24f1960a91c82cf67619395b60b564c90e9e5d5325fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73a087aa3bd279fb70d24f1960a91c82cf67619395b60b564c90e9e5d5325fc?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"News e aggiornamenti sui film, serie tv, teatro e festival italiani ed internazionali.\",\"url\":\"https:\\\/\\\/www.castingnews.eu\\\/magazine\\\/author\\\/redazione\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona - Casting News Magazine","description":"Sono iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, diretto da Valentina Zanella e tratto dal romanzo di Alessia Gazzola.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/","og_locale":"it_IT","og_type":"article","og_title":"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona - Casting News Magazine","og_description":"Sono iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, diretto da Valentina Zanella e tratto dal romanzo di Alessia Gazzola.","og_url":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/","og_site_name":"Casting News Magazine","article_published_time":"2025-07-13T18:52:22+00:00","article_modified_time":"2025-07-13T18:52:24+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/www.castingnews.eu\/magazine\/wp-content\/uploads\/2025\/07\/Verona-Veneto-film-Casting-News.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#article","isPartOf":{"@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/"},"author":{"name":"Redazione","@id":"https:\/\/www.castingnews.eu\/magazine\/#\/schema\/person\/099d71c568c9a7e5e4037b1594108f17"},"headline":"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona","datePublished":"2025-07-13T18:52:22+00:00","dateModified":"2025-07-13T18:52:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/"},"wordCount":342,"commentCount":0,"image":{"@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.castingnews.eu\/magazine\/wp-content\/uploads\/2025\/07\/Verona-Veneto-film-Casting-News.jpg","keywords":["adattamento cinematografico","Alessia Gazzola romanzo","Andrea Bosca attore","Casting Magazine","Casting News","cinema italiano 2026","distribuzione film 2026","film girato a Verona","film italiani 2025","film tratto da romanzo","Fondazione Veneto Film Commission","Fotin\u00ec Peluso attrice","K Plus Film","Non \u00e8 la fine del mondo film","Paolo Rossi attore","Paolo Ruffini cast","produzione cinematografica Verona","riprese Verona","Valentina Zanella regista"],"articleSection":["Commedia","In primo piano","Italia","Primo piano","Progetti cinematografici","Romantico","Veneto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/","url":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/","name":"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona - Casting News Magazine","isPartOf":{"@id":"https:\/\/www.castingnews.eu\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#primaryimage"},"image":{"@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.castingnews.eu\/magazine\/wp-content\/uploads\/2025\/07\/Verona-Veneto-film-Casting-News.jpg","datePublished":"2025-07-13T18:52:22+00:00","dateModified":"2025-07-13T18:52:24+00:00","author":{"@id":"https:\/\/www.castingnews.eu\/magazine\/#\/schema\/person\/099d71c568c9a7e5e4037b1594108f17"},"description":"Sono iniziate a Verona le riprese del film Non \u00e8 la fine del mondo, diretto da Valentina Zanella e tratto dal romanzo di Alessia Gazzola.","breadcrumb":{"@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#primaryimage","url":"https:\/\/www.castingnews.eu\/magazine\/wp-content\/uploads\/2025\/07\/Verona-Veneto-film-Casting-News.jpg","contentUrl":"https:\/\/www.castingnews.eu\/magazine\/wp-content\/uploads\/2025\/07\/Verona-Veneto-film-Casting-News.jpg","width":1200,"height":670,"caption":"Riprese a Verona per il film \u201cNon \u00e8 la fine del mondo\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.castingnews.eu\/magazine\/2025\/07\/13\/valentina-zanella-porta-sul-grande-schermo-non-e-la-fine-del-mondo-al-via-le-riprese-a-verona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.castingnews.eu\/magazine\/"},{"@type":"ListItem","position":2,"name":"Valentina Zanella porta sul grande schermo \u201cNon \u00e8 la fine del mondo\u201d: al via le riprese a Verona"}]},{"@type":"WebSite","@id":"https:\/\/www.castingnews.eu\/magazine\/#website","url":"https:\/\/www.castingnews.eu\/magazine\/","name":"Casting News Magazine","description":"News e aggiornamenti sui film, serie tv, teatro e festival italiani ed internazionali","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.castingnews.eu\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.castingnews.eu\/magazine\/#\/schema\/person\/099d71c568c9a7e5e4037b1594108f17","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b73a087aa3bd279fb70d24f1960a91c82cf67619395b60b564c90e9e5d5325fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b73a087aa3bd279fb70d24f1960a91c82cf67619395b60b564c90e9e5d5325fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b73a087aa3bd279fb70d24f1960a91c82cf67619395b60b564c90e9e5d5325fc?s=96&d=mm&r=g","caption":"Redazione"},"description":"News e aggiornamenti sui film, serie tv, teatro e festival italiani ed internazionali.","url":"https:\/\/www.castingnews.eu\/magazine\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/posts\/10520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/comments?post=10520"}],"version-history":[{"count":1,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/posts\/10520\/revisions"}],"predecessor-version":[{"id":10523,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/posts\/10520\/revisions\/10523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/media\/10522"}],"wp:attachment":[{"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/media?parent=10520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/categories?post=10520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.castingnews.eu\/magazine\/wp-json\/wp\/v2\/tags?post=10520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}